{"id":8362,"date":"2018-04-30T23:17:32","date_gmt":"2018-04-30T21:17:32","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/"},"modified":"2018-05-02T00:36:06","modified_gmt":"2018-05-01T22:36:06","slug":"nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/","title":{"rendered":"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil"},"content":{"rendered":"<p>[et_pb_section bb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb custom_padding=\u00bb2px|0px|54px|0px\u00bb][et_pb_row admin_label=\u00bbrow\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_size=\u00bbinitial\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text admin_label=\u00bbAutor\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.2&#8243;]<\/p>\n<p>Por\u00a0Antonio Gil<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbEntradilla\u00bb text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.2&#8243;]<\/p>\n<p><em><strong>Quiero agradeceros, con emoci\u00f3n contenida todav\u00eda, todo lo que me hab\u00e9is hecho disfrutar, reflexionar, recordar, revivir en estos d\u00edas y especialmente en esa entra\u00f1able celebraci\u00f3n del domingo 29.<\/strong><\/em><\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb _builder_version=\u00bb3.2&#8243;]<\/p>\n<p><strong>BODAS DE ORO SACERDOTALES<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-8363\" src=\"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/05\/Antonio-Gil_2-300x208.jpg\" alt=\"\" width=\"300\" height=\"208\" \/><\/strong><\/p>\n<p><strong>pidiendo al Se\u00f1or mantenga siempre el coraz\u00f3n joven<\/strong><\/p>\n<p><strong>Sencillamente\u2026\u00a1\u00a1\u00a1GRACIAS!!!<\/strong><\/p>\n<p><strong>\u2026 como si no hubiera pasado el tiempo \u2026<\/strong><\/p>\n<p><strong>50 a\u00f1os \u2013Bodas de oro- de mi sacerdocio -\u00bf50?-, \u00a1qui\u00e9n lo dir\u00eda!<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Quiero agradeceros con emoci\u00f3n contenida todav\u00eda todo lo que me hab\u00e9is hecho disfrutar, reflexionar, recordar, revivir en estos d\u00edas y especialmente en esa entra\u00f1able celebraci\u00f3n del domingo 29\u2026 \u00a1cu\u00e1ntos recuerdos!&#8230; s\u00ed, sencillamente \u00a1\u00a1\u00a1GRACIAS!!!<\/p>\n<p>Detr\u00e1s quedan muchos rostros, hermanos, j\u00f3venes, sobre todo ni\u00f1os y j\u00f3venes, gentes buenas con los que he ido compartiendo mi peque\u00f1a y prolongada realidad existencial en la senda de la vida, siguiendo las huellas de Juan Bosco so\u00f1ador, con el amparo de la Madre Auxiliadora\u2026 y el cari\u00f1o, tambi\u00e9n el vuestro, que ha ido adornando el itinerario que me ha tocado transitar\u2026<\/p>\n<p>Y siempre sorprendido, y ahora entre vosotros, en esta ya mi querida M\u00e1laga, no ha sido menos\u2026 Siento que a trav\u00e9s de vuestras vidas el Dios bueno sigue enriqueciendo la m\u00eda. Vuestra cercan\u00eda y la emoci\u00f3n compartida me une y compromete\u2026<\/p>\n<p>Las cosas suceden y la vida se va entretejiendo entre momentos muy hermosos, dudas, cansancios, ilusiones renovadas y horizontes que se van despejando. Siempre he sentido que deb\u00eda seguir\u2026 Y aqu\u00ed estoy\u2026 y sigo so\u00f1ando como en tantos acontecimientos y expresiones de creatividad y vida\u2026 hasta que \u00c9l quiera\u2026 porque 50 a\u00f1os despu\u00e9s:<\/p>\n<blockquote>\n<p style=\"text-align: center;\"><em><strong>Sigo siendo peregrino<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>del amor y la esperanza;<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>y sigo siendo el amigo<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>m\u00e1s cargado de a\u00f1oranzas;<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>sigo labrando el destino<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>y ofreciendo mi alianza<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>con coraz\u00f3n expresivo,<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>con sue\u00f1os que me dan alas;<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>Quiero seguir siendo el mismo;<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>en mi querida M\u00e1laga<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>seguir luchando contigo<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>con el querer de mi alma;<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>sentirme cercano y vivo<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>a la vida que nos llama;<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>agradecer lo vivido<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>seguir abriendo ventanas<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>para compartir contigo<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>el amor que Dios regala&#8230;<\/strong><\/em><\/p>\n<\/blockquote>\n<p>Te quiero M\u00e1laga. Os quiero Familia Salesiana, amigos\u2026<\/p>\n<p><strong>Antonio<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb3.2&#8243;]<\/p>\n<h1>Galer\u00eda multimedia<\/h1>\n<p>[\/et_pb_text][et_pb_video _builder_version=\u00bb3.2&#8243; src=\u00bbhttps:\/\/youtu.be\/G2D3RiSKLqU\u00bb image_src=\u00bb\/\/i.ytimg.com\/vi\/G2D3RiSKLqU\/hqdefault.jpg\u00bb \/][et_pb_gallery _builder_version=\u00bb3.2&#8243; gallery_ids=\u00bb8383,8382,8381,8380,8375&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#dc001b\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.9)\u00bb gallery_orderby=\u00bbrand\u00bb \/][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quiero agradeceros, con emoci\u00f3n contenida todav\u00eda, todo lo que me hab\u00e9is hecho disfrutar, reflexionar, recordar, revivir en estos d\u00edas y especialmente en esa entra\u00f1able celebraci\u00f3n del domingo 29.<\/p>\n","protected":false},"author":2,"featured_media":8363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[113,101,112],"tags":[],"class_list":["post-8362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-familia-salesiana","category-santuario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil - Familia Salesiana | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil - Familia Salesiana | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Quiero agradeceros, con emoci\u00f3n contenida todav\u00eda, todo lo que me hab\u00e9is hecho disfrutar, reflexionar, recordar, revivir en estos d\u00edas y especialmente en esa entra\u00f1able celebraci\u00f3n del domingo 29.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/\" \/>\n<meta property=\"og:site_name\" content=\"Familia Salesiana | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-30T21:17:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-01T22:36:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/04\/Antonio-Gil_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n MLG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n MLG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n MLG\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\"},\"headline\":\"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil\",\"datePublished\":\"2018-04-30T21:17:32+00:00\",\"dateModified\":\"2018-05-01T22:36:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/\"},\"wordCount\":556,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2018\\\/04\\\/Antonio-Gil_2.jpg\",\"articleSection\":[\"Casa\",\"Familia Salesiana\",\"Santuario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/\",\"name\":\"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil - Familia Salesiana | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2018\\\/04\\\/Antonio-Gil_2.jpg\",\"datePublished\":\"2018-04-30T21:17:32+00:00\",\"dateModified\":\"2018-05-01T22:36:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2018\\\/04\\\/Antonio-Gil_2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2018\\\/04\\\/Antonio-Gil_2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/\",\"name\":\"Familia Salesiana | Salesianos M\u00e1laga\",\"description\":\"Familia Salesiana | Salesianos M\u00e1laga, ADMA, Asociaci\u00f3n de antiguos alumnos, Hermandad Salesiana, Salesianos Cooperadores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\",\"name\":\"Comunicaci\u00f3n MLG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n MLG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil - Familia Salesiana | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/","og_locale":"es_ES","og_type":"article","og_title":"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil - Familia Salesiana | Salesianos M\u00e1laga","og_description":"Quiero agradeceros, con emoci\u00f3n contenida todav\u00eda, todo lo que me hab\u00e9is hecho disfrutar, reflexionar, recordar, revivir en estos d\u00edas y especialmente en esa entra\u00f1able celebraci\u00f3n del domingo 29.","og_url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/","og_site_name":"Familia Salesiana | Salesianos M\u00e1laga","article_published_time":"2018-04-30T21:17:32+00:00","article_modified_time":"2018-05-01T22:36:06+00:00","og_image":[{"url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/04\/Antonio-Gil_2.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Comunicaci\u00f3n MLG","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3n MLG","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/"},"author":{"name":"Comunicaci\u00f3n MLG","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b"},"headline":"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil","datePublished":"2018-04-30T21:17:32+00:00","dateModified":"2018-05-01T22:36:06+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/"},"wordCount":556,"commentCount":0,"image":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/04\/Antonio-Gil_2.jpg","articleSection":["Casa","Familia Salesiana","Santuario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/","url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/","name":"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil - Familia Salesiana | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/04\/Antonio-Gil_2.jpg","datePublished":"2018-04-30T21:17:32+00:00","dateModified":"2018-05-01T22:36:06+00:00","author":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b"},"breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/04\/Antonio-Gil_2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/04\/Antonio-Gil_2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/nota-de-agradecimiento-por-las-bodas-de-oro-sacerdotales-de-d-antonio-gil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/"},{"@type":"ListItem","position":2,"name":"Nota de agradecimiento por las Bodas de Oro Sacerdotales de D. Antonio Gil"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#website","url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/","name":"Familia Salesiana | Salesianos M\u00e1laga","description":"Familia Salesiana | Salesianos M\u00e1laga, ADMA, Asociaci\u00f3n de antiguos alumnos, Hermandad Salesiana, Salesianos Cooperadores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b","name":"Comunicaci\u00f3n MLG","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n MLG"}}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/8362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/comments?post=8362"}],"version-history":[{"count":20,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/8362\/revisions"}],"predecessor-version":[{"id":8388,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/8362\/revisions\/8388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/media\/8363"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/media?parent=8362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/categories?post=8362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/tags?post=8362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}