{"id":4820,"date":"2017-02-26T23:54:37","date_gmt":"2017-02-26T22:54:37","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/don-bosco-en-espana-2\/"},"modified":"2017-10-26T23:56:08","modified_gmt":"2017-10-26T21:56:08","slug":"don-bosco-en-espana-2","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/","title":{"rendered":"Don Bosco en Espa\u00f1a"},"content":{"rendered":"<p>[et_pb_section admin_label=\u00bbsection\u00bb][et_pb_row admin_label=\u00bbrow\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text admin_label=\u00bbAutor\u00bb background_layout=\u00bblight\u00bb text_orientation=\u00bbleft\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p>Por Jos\u00e9 D. Farr\u00e9 Portales<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbEntradilla\u00bb background_layout=\u00bblight\u00bb text_orientation=\u00bbleft\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb text_font=\u00bb|on|||\u00bb]<\/p>\n<p><em><strong>Pues s\u00ed, Don Bosco estuvo en Espa\u00f1a. Y la Espa\u00f1a que visit\u00f3 se rindi\u00f3 a Don Bosco de una manera apasionada y total. El fundador de los salesianos pas\u00f3 un mes en Barcelona en 1886. Hoy les hablar\u00e9, mis queridos amigos lectores, de esa visita y sus circunstancias. Si gustan, pasen y lean.<\/strong><\/em><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb background_layout=\u00bblight\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-496 size-medium\" src=\"http:\/\/malagaold.salesianos.edu\/wp-content\/uploads\/2017\/02\/boscobcn_560x280-300x150.jpg\" width=\"300\" height=\"150\" \/>En 1886 Don Bosco ya estaba con la salud muy quebrantada, fallecer\u00eda en 1888, pero a\u00fan conservaba todo su magnetismo personal y su fama de santo era ya inmensa. Adem\u00e1s su m\u00e9todo educativo, el Sistema Preventivo, contaba ya con la admiraci\u00f3n de medio mundo. Su sistema educativo es la gran obra de Juan Bosco. Un verdadero monumento de humana pedagog\u00eda que seguimos aplicando con \u00e9xito tantos a\u00f1os despu\u00e9s a lo largo y ancho de nuestro planeta, en 132 pa\u00edses, no solamente en colegios sino en oratorios y centros juveniles, en casas y hogares de acogida, en parroquias y obras salesianas que est\u00e1n en contacto con j\u00f3venes.<\/p>\n<p style=\"text-align: left;\">Y hay que decir, adem\u00e1s, que su pedagog\u00eda tiene un fuerte componente social, que unido al esp\u00edritu evangelizador, le da su gran fuerza. El Sistema Preventivo est\u00e1 dedicado al trabajo con j\u00f3venes explotados, abandonados o desfavorecidos. Los salesianos, aun cuando atienden a alumnos de todo tipo y origen, tienen su raz\u00f3n de ser en el \u201crescate\u201d de chavales j\u00f3venes que de otro modo se convertir\u00edan en \u201ccarne de ca\u00f1\u00f3n\u201d para una sociedad capitalista que devora la dignidad de las personas, y m\u00e1s la de los j\u00f3venes sin autoestima, formaci\u00f3n ni cualificaci\u00f3n.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-497 size-medium\" src=\"http:\/\/malagaold.salesianos.edu\/wp-content\/uploads\/2017\/02\/31deenerosanjuanbosco-300x189.jpg\" width=\"300\" height=\"189\" \/>Es, por tanto, la educaci\u00f3n un resultado del amor. Dec\u00eda Don Bosco: \u201cSin amor no puede haber confianza y sin confianza no puede haber educaci\u00f3n\u201d. Cuando el\u00a0 alumno se siente en un ambiente familiar en el que es querido y aceptado como persona ( y pensemos en los primeros alumnos de los colegios salesianos : ni\u00f1os abandonados, desechos de la sociedad de su tiempo) se produce el milagro por el que el maestro tiene con seguridad en sus manos el coraz\u00f3n del alumno y puede con procedimientos suaves, sin choques ni sacudimientos, llevarlo hacia el bien, la cultura y la religi\u00f3n.<\/p>\n<p style=\"text-align: left;\">Prevenir impidiendo con cari\u00f1o que se tuerza el arbolito de las almas infantiles y juveniles. Don Bosco, que conoc\u00eda bien las cuatro c\u00e1rceles de Tur\u00edn, sab\u00eda que una vez torcida una vida es muy dif\u00edcil de enderezar. Es mejor prevenir. Y hacerlo con cari\u00f1o y sin violencia. Y con alegr\u00eda.<\/p>\n<p style=\"text-align: left;\">Todo esto ya estaba en las mentes de los que, el 8 de Abril de 1886, esperaban expectantes en la estaci\u00f3n de ferrocarril la llegada de un tren con un vag\u00f3n especial en el que viajaban Don Bosco y su fiel secretario Don Viglietti. Barcelona era, junto a\u00a0 M\u00e1laga, una de las primeras ciudades espa\u00f1olas en donde la juventud sufre la explotaci\u00f3n de la industrializaci\u00f3n. \u00a0Dos a\u00f1os antes ya se hab\u00eda fundado en Barcelona el colegio de Sarri\u00e1 y la benem\u00e9rita obra salesiana ya era conocida en toda la ciudad. Don Bosco se entregar\u00eda en cuerpo y alma a una intensa visita llena de satisfacciones y de reconocimientos. Hoy la habitaci\u00f3n en la que residi\u00f3 Juan Bosco est\u00e1 convertida en una hermosa capilla de estilo modernista.<\/p>\n<p style=\"text-align: left;\">Las \u201cMemorias Biogr\u00e1ficas\u201d, en el volumen XVIII ofrecen una cr\u00f3nica detallada de cada uno de\u00a0 los d\u00edas que Don Bosco permanece en la ciudad condal. Y nos presentan a un hombre agotado y extenuado, s\u00ed, pero inmensamente feliz de ver c\u00f3mo lo rodean y lo quieren los chicos y los grandes.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-498 size-medium\" src=\"http:\/\/malagaold.salesianos.edu\/wp-content\/uploads\/2017\/02\/fondobosco-300x201.jpg\" width=\"300\" height=\"201\" \/>El Correo Catal\u00e1n se hace eco de este ambiente. \u201cBarcelona entera, representada por todas las clases sociales, ha recibido con alegr\u00eda la visita de un sacerdote cargado de m\u00e9ritos, al que damos nuestra cordial bienvenida\u201d. Fue, ciertamente una visita de una actividad ingente, de muchas recepciones y entrevistas con los bienhechores que est\u00e1n haciendo posible que la obra salesiana crezca en Sarri\u00e1: do\u00f1a Dorotea Chopitea, don Luis Mart\u00ed-Colomar y don Narciso Pascual, entre otros. Las cr\u00f3nicas de aquellos d\u00edas recogen c\u00f3mo hab\u00eda masas de gentes que quer\u00edan conocerle y recibir su bendici\u00f3n. Dignatarios eclesi\u00e1sticos, superiores religiosos y autoridades\u00a0 civiles le presentaron sus respetos. La gente de la nobleza compite por tenerle como invitado.<\/p>\n<p style=\"text-align: left;\">Tambi\u00e9n recibe la donaci\u00f3n que se le hace de los terrenos de la cumbre del Tibidabo, que es la colina m\u00e1s alta del entorno de Barcelona y goza de una vista impresionante de la ciudad, sus alrededores y el mar. El 5 de Mayo Don Bosco recibe un diploma en el que se hace constar la donaci\u00f3n de la propiedad a fin de que los salesianos edifiquen all\u00ed un templo consagrado al Coraz\u00f3n de Jes\u00fas. Hoy el templo es una hermosa realidad y un visible recuerdo de esta memorable visita.<\/p>\n<p style=\"text-align: left;\">Don Bosco finaliza su visita el 6 de mayo, partiendo en tren desde una estaci\u00f3n atiborrada de personas de todas las clases sociales que desean recibir su \u00faltima bendici\u00f3n. Juan Bosco marcha cansado y agotado pero muy feliz por la acogida que hab\u00eda recibido en Espa\u00f1a. Una Espa\u00f1a que abr\u00eda sus brazos a la obra de los salesianos, que hab\u00edan fundado por primera vez en Utrera en 1881, y eran invitados a fundar en todas las regiones de una naci\u00f3n deseosa de recibir a los hijos de Don Bosco y los beneficios del Sistema Preventivo para sus j\u00f3venes necesitados de formaci\u00f3n y autoestima.<\/p>\n<p style=\"text-align: left;\">Jos\u00e9 Diego Farr\u00e9 Portales. Profesor del Colegio Salesiano de M\u00e1laga<\/p>\n<p style=\"text-align: left;\">Publicado en DIARIO SUR\u00a0 28-1-2017\u00a0\u00a0\u00a0 Pg.40<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pues s\u00ed, Don Bosco estuvo en Espa\u00f1a. Y la Espa\u00f1a que visit\u00f3 se rindi\u00f3 a Don Bosco de una manera apasionada y total.<\/p>\n","protected":false},"author":2,"featured_media":4821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p><em><strong>Pues s\u00ed, Don Bosco estuvo en Espa\u00f1a. Y la Espa\u00f1a que visit\u00f3 se rindi\u00f3 a Don Bosco de una manera apasionada y total. El fundador de los salesianos pas\u00f3 un mes en Barcelona en 1886. Hoy les hablar\u00e9, mis queridos amigos lectores, de esa visita y sus circunstancias. Si gustan, pasen y lean.<\/strong><\/em><\/p><hr \/><p><a href=\"https:\/\/malaga.salesianos.edu\/wp-content\/uploads\/2017\/02\/boscobcn_560x280.jpg\"><img class=\"alignleft wp-image-496 size-medium\" src=\"https:\/\/malaga.salesianos.edu\/wp-content\/uploads\/2017\/02\/boscobcn_560x280-300x150.jpg\" width=\"300\" height=\"150\" \/><\/a>En 1886 Don Bosco ya estaba con la salud muy quebrantada, fallecer\u00eda en 1888, pero a\u00fan conservaba todo su magnetismo personal y su fama de santo era ya inmensa. Adem\u00e1s su m\u00e9todo educativo, el Sistema Preventivo, contaba ya con la admiraci\u00f3n de medio mundo. Su sistema educativo es la gran obra de Juan Bosco. Un verdadero monumento de humana pedagog\u00eda que seguimos aplicando con \u00e9xito tantos a\u00f1os despu\u00e9s a lo largo y ancho de nuestro planeta, en 132 pa\u00edses, no solamente en colegios sino en oratorios y centros juveniles, en casas y hogares de acogida, en parroquias y obras salesianas que est\u00e1n en contacto con j\u00f3venes.<\/p><p>\u00a0<\/p><p>Y hay que decir, adem\u00e1s, que su pedagog\u00eda tiene un fuerte componente social, que unido al esp\u00edritu evangelizador, le da su gran fuerza. El Sistema Preventivo est\u00e1 dedicado al trabajo con j\u00f3venes explotados, abandonados o desfavorecidos. Los salesianos, aun cuando atienden a alumnos de todo tipo y origen, tienen su raz\u00f3n de ser en el \u201crescate\u201d de chavales j\u00f3venes que de otro modo se convertir\u00edan en \u201ccarne de ca\u00f1\u00f3n\u201d para una sociedad capitalista que devora la dignidad de las personas, y m\u00e1s la de los j\u00f3venes sin autoestima, formaci\u00f3n ni cualificaci\u00f3n.<\/p><p><a href=\"https:\/\/malaga.salesianos.edu\/wp-content\/uploads\/2017\/02\/31deenerosanjuanbosco.jpg\"><img class=\"alignleft size-medium wp-image-497\" src=\"https:\/\/malaga.salesianos.edu\/wp-content\/uploads\/2017\/02\/31deenerosanjuanbosco-300x189.jpg\" alt=\"\" width=\"300\" height=\"189\" \/><\/a>Es, por tanto, la educaci\u00f3n un resultado del amor. Dec\u00eda Don Bosco: \u201cSin amor no puede haber confianza y sin confianza no puede haber educaci\u00f3n\u201d. Cuando el\u00a0 alumno se siente en un ambiente familiar en el que es querido y aceptado como persona ( y pensemos en los primeros alumnos de los colegios salesianos : ni\u00f1os abandonados, desechos de la sociedad de su tiempo) se produce el milagro por el que el maestro tiene con seguridad en sus manos el coraz\u00f3n del alumno y puede con procedimientos suaves, sin choques ni sacudimientos, llevarlo hacia el bien, la cultura y la religi\u00f3n.<\/p><p>Prevenir impidiendo con cari\u00f1o que se tuerza el arbolito de las almas infantiles y juveniles. Don Bosco, que conoc\u00eda bien las cuatro c\u00e1rceles de Tur\u00edn, sab\u00eda que una vez torcida una vida es muy dif\u00edcil de enderezar. Es mejor prevenir. Y hacerlo con cari\u00f1o y sin violencia. Y con alegr\u00eda.<\/p><p>Todo esto ya estaba en las mentes de los que, el 8 de Abril de 1886, esperaban expectantes en la estaci\u00f3n de ferrocarril la llegada de un tren con un vag\u00f3n especial en el que viajaban Don Bosco y su fiel secretario Don Viglietti. Barcelona era, junto a\u00a0 M\u00e1laga, una de las primeras ciudades espa\u00f1olas en donde la juventud sufre la explotaci\u00f3n de la industrializaci\u00f3n. \u00a0Dos a\u00f1os antes ya se hab\u00eda fundado en Barcelona el colegio de Sarri\u00e1 y la benem\u00e9rita obra salesiana ya era conocida en toda la ciudad. Don Bosco se entregar\u00eda en cuerpo y alma a una intensa visita llena de satisfacciones y de reconocimientos. Hoy la habitaci\u00f3n en la que residi\u00f3 Juan Bosco est\u00e1 convertida en una hermosa capilla de estilo modernista.<\/p><p>Las \u201cMemorias Biogr\u00e1ficas\u201d, en el volumen XVIII ofrecen una cr\u00f3nica detallada de cada uno de\u00a0 los d\u00edas que Don Bosco permanece en la ciudad condal. Y nos presentan a un hombre agotado y extenuado, s\u00ed, pero inmensamente feliz de ver c\u00f3mo lo rodean y lo quieren los chicos y los grandes.<\/p><p><a href=\"https:\/\/malaga.salesianos.edu\/wp-content\/uploads\/2017\/02\/fondobosco.jpg\"><img class=\"size-medium wp-image-498 alignright\" src=\"https:\/\/malaga.salesianos.edu\/wp-content\/uploads\/2017\/02\/fondobosco-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" \/><\/a>El Correo Catal\u00e1n se hace eco de este ambiente. \u201cBarcelona entera, representada por todas las clases sociales, ha recibido con alegr\u00eda la visita de un sacerdote cargado de m\u00e9ritos, al que damos nuestra cordial bienvenida\u201d. Fue, ciertamente una visita de una actividad ingente, de muchas recepciones y entrevistas con los bienhechores que est\u00e1n haciendo posible que la obra salesiana crezca en Sarri\u00e1: do\u00f1a Dorotea Chopitea, don Luis Mart\u00ed-Colomar y don Narciso Pascual, entre otros. Las cr\u00f3nicas de aquellos d\u00edas recogen c\u00f3mo hab\u00eda masas de gentes que quer\u00edan conocerle y recibir su bendici\u00f3n. Dignatarios eclesi\u00e1sticos, superiores religiosos y autoridades\u00a0 civiles le presentaron sus respetos. La gente de la nobleza compite por tenerle como invitado.<\/p><p>Tambi\u00e9n recibe la donaci\u00f3n que se le hace de los terrenos de la cumbre del Tibidabo, que es la colina m\u00e1s alta del entorno de Barcelona y goza de una vista impresionante de la ciudad, sus alrededores y el mar. El 5 de Mayo Don Bosco recibe un diploma en el que se hace constar la donaci\u00f3n de la propiedad a fin de que los salesianos edifiquen all\u00ed un templo consagrado al Coraz\u00f3n de Jes\u00fas. Hoy el templo es una hermosa realidad y un visible recuerdo de esta memorable visita.<\/p><p>Don Bosco finaliza su visita el 6 de mayo, partiendo en tren desde una estaci\u00f3n atiborrada de personas de todas las clases sociales que desean recibir su \u00faltima bendici\u00f3n. Juan Bosco marcha cansado y agotado pero muy feliz por la acogida que hab\u00eda recibido en Espa\u00f1a. Una Espa\u00f1a que abr\u00eda sus brazos a la obra de los salesianos, que hab\u00edan fundado por primera vez en Utrera en 1881, y eran invitados a fundar en todas las regiones de una naci\u00f3n deseosa de recibir a los hijos de Don Bosco y los beneficios del Sistema Preventivo para sus j\u00f3venes necesitados de formaci\u00f3n y autoestima.<\/p><p>Jos\u00e9 Diego Farr\u00e9 Portales. Profesor del Colegio Salesiano de M\u00e1laga<\/p><p>Publicado en DIARIO SUR\u00a0 28-1-2017\u00a0\u00a0\u00a0 Pg.40<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[101],"tags":[39,50,54],"class_list":["post-4820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familia-salesiana","tag-familia-salesiana","tag-prensa","tag-publicaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Don Bosco en Espa\u00f1a - Familia Salesiana | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Don Bosco en Espa\u00f1a - Familia Salesiana | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Pues s\u00ed, Don Bosco estuvo en Espa\u00f1a. Y la Espa\u00f1a que visit\u00f3 se rindi\u00f3 a Don Bosco de una manera apasionada y total.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Familia Salesiana | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-26T22:54:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-26T21:56:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2017\/10\/boscobcn_560x280-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n MLG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n MLG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n MLG\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\"},\"headline\":\"Don Bosco en Espa\u00f1a\",\"datePublished\":\"2017-02-26T22:54:37+00:00\",\"dateModified\":\"2017-10-26T21:56:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/\"},\"wordCount\":1088,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2017\\\/10\\\/boscobcn_560x280-1.jpg\",\"keywords\":[\"Familia Salesiana\",\"Prensa\",\"Publicaciones\"],\"articleSection\":[\"Familia Salesiana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/\",\"name\":\"Don Bosco en Espa\u00f1a - Familia Salesiana | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2017\\\/10\\\/boscobcn_560x280-1.jpg\",\"datePublished\":\"2017-02-26T22:54:37+00:00\",\"dateModified\":\"2017-10-26T21:56:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2017\\\/10\\\/boscobcn_560x280-1.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2017\\\/10\\\/boscobcn_560x280-1.jpg\",\"width\":560,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/blog\\\/don-bosco-en-espana-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Don Bosco en Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/\",\"name\":\"Familia Salesiana | Salesianos M\u00e1laga\",\"description\":\"Familia Salesiana | Salesianos M\u00e1laga, ADMA, Asociaci\u00f3n de antiguos alumnos, Hermandad Salesiana, Salesianos Cooperadores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\",\"name\":\"Comunicaci\u00f3n MLG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n MLG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Don Bosco en Espa\u00f1a - Familia Salesiana | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/","og_locale":"es_ES","og_type":"article","og_title":"Don Bosco en Espa\u00f1a - Familia Salesiana | Salesianos M\u00e1laga","og_description":"Pues s\u00ed, Don Bosco estuvo en Espa\u00f1a. Y la Espa\u00f1a que visit\u00f3 se rindi\u00f3 a Don Bosco de una manera apasionada y total.","og_url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/","og_site_name":"Familia Salesiana | Salesianos M\u00e1laga","article_published_time":"2017-02-26T22:54:37+00:00","article_modified_time":"2017-10-26T21:56:08+00:00","og_image":[{"width":560,"height":280,"url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2017\/10\/boscobcn_560x280-1.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n MLG","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3n MLG","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/"},"author":{"name":"Comunicaci\u00f3n MLG","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b"},"headline":"Don Bosco en Espa\u00f1a","datePublished":"2017-02-26T22:54:37+00:00","dateModified":"2017-10-26T21:56:08+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/"},"wordCount":1088,"commentCount":0,"image":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2017\/10\/boscobcn_560x280-1.jpg","keywords":["Familia Salesiana","Prensa","Publicaciones"],"articleSection":["Familia Salesiana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/","url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/","name":"Don Bosco en Espa\u00f1a - Familia Salesiana | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2017\/10\/boscobcn_560x280-1.jpg","datePublished":"2017-02-26T22:54:37+00:00","dateModified":"2017-10-26T21:56:08+00:00","author":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b"},"breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2017\/10\/boscobcn_560x280-1.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2017\/10\/boscobcn_560x280-1.jpg","width":560,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/blog\/don-bosco-en-espana-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/"},{"@type":"ListItem","position":2,"name":"Don Bosco en Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#website","url":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/","name":"Familia Salesiana | Salesianos M\u00e1laga","description":"Familia Salesiana | Salesianos M\u00e1laga, ADMA, Asociaci\u00f3n de antiguos alumnos, Hermandad Salesiana, Salesianos Cooperadores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b","name":"Comunicaci\u00f3n MLG","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n MLG"}}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/4820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/comments?post=4820"}],"version-history":[{"count":1,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/4820\/revisions"}],"predecessor-version":[{"id":4822,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/4820\/revisions\/4822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/media\/4821"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/media?parent=4820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/categories?post=4820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/tags?post=4820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}