{"id":89293,"date":"2023-11-17T10:15:44","date_gmt":"2023-11-17T09:10:37","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico\/"},"modified":"2023-11-17T10:16:29","modified_gmt":"2023-11-17T09:16:29","slug":"nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/","title":{"rendered":"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; text_orientation=\u00bbjustified\u00bb]<\/p>\n<p>Alguien dijo alguna vez: \u201cLo m\u00e1s valioso de la vida no es lo que tenemos, sino a quien tenemos\u201d.<\/p>\n<p>El pasado 26 y 27 de octubre y 02 de noviembre, contamos con la colaboraci\u00f3n de la Asociaci\u00f3n AESLEME bajo la representaci\u00f3n de Sergio Hijano para ofrecernos unas charlas formativas para la sensibilizaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico.<\/p>\n<p>Nunca ha tenido m\u00e1s sentido esta expresi\u00f3n, \u201cLo m\u00e1s valioso de la vida no es lo que tenemos, sino a quien tenemos\u201d, a partir de la experiencia aportada por Sergio. En cualquier momento nuestra vida puede cambiar, dar un giro inesperado que hace replantearnos que lo m\u00e1s valioso que podemos tener es a nosotros\/as mismos\/as y nuestros seres queridos.<\/p>\n<p>Sergio nos regal\u00f3 un gran discurso de c\u00f3mo debemos aprovechar nuestra maravillosa vida, y evitar situaciones que pongan en peligro su continuidad. Nos habl\u00f3 de la importancia de reducir el porcentaje de riesgo de un accidente llevando a cabo una actitud c\u00edvica y de prevenci\u00f3n que favorezcan el que no se produzcan accidentes de tr\u00e1fico.<\/p>\n<p>Es verdad que hay numerosas variables indirectas que pueden provocar en un momento determinado un accidente, \u00e9stas no podemos controlarlas; pero las variables directas s\u00ed, como por ejemplo: no uso del m\u00f3vil durante la conducci\u00f3n, no ingesta de alcohol si se va a utilizar un veh\u00edculo, no consumo de sustancias adictivas, control de velocidad, uso adecuado de cinturones de seguridad, llevar casco adecuado, \u2026.. <br \/>Todas\/os formamos parte de una sociedad, de la que todas\/os somos responsables de su buen funcionamiento, pues\u2026\u2026..vamos a ponerlo en pr\u00e1ctica. Vamos a poner nuestro granito de arena para que podamos seguir disfrutando de los que tenemos y de nuestra propia vida.<\/p>\n<p>\u201cCuando aprendes a valorar las peque\u00f1as cosas de la vida, aprendes a vivir\u201d (Earl Nightingale)<\/p>\n<p>Os invitamos a seguir la cuenta en Instagram de Aesleme y de Sergio Hijano para seguir creando conciencias, seguir favoreciendo una sociedad responsable y en el bien com\u00fan. Adem\u00e1s de ayudar a las personas v\u00edctimas de tr\u00e1fico para su autonom\u00eda y desarrollo integral, y crear conciencia a nivel social para crear espacios accesibles e inclusivos.<\/p>\n<p>[\/et_pb_text][et_pb_gallery _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; gallery_ids=\u00bb81555,81556,81557,81558,81559,81560,81561,81562,81563,81564,81565,81566&#8243; show_title_and_caption=\u00bboff\u00bb][\/et_pb_gallery][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Sigue a Aesleme y Sergio Hijano en las redes sociales:<\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; text_orientation=\u00bbcenter\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb42px\u00bb animation_style=\u00bbslide\u00bb][et_pb_social_media_follow_network _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb social_network=\u00bbinstagram\u00bb background_color=\u00bb#ea2c59&#8243; url=\u00bbhttps:\/\/www.instagram.com\/aesleme_espana\/\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb30px\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb social_network=\u00bbinstagram\u00bb background_color=\u00bb#ea2c59&#8243; url=\u00bbhttps:\/\/www.instagram.com\/sergiohijano\/?utm_source=ig_embed&#038;ig_rid=f975af9a-b26a-4063-9eb7-772b2e5592db&#038;ig_mid=D75D19FC-456D-401F-83BD-F518EF93DB27&#8243; hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb30px\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb social_network=\u00bbtwitter\u00bb background_color=\u00bb#000000&#8243; url=\u00bbhttps:\/\/twitter.com\/sergiohijano?lang=es\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb30px\u00bb]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb social_network=\u00bbyoutube\u00bb background_color=\u00bb#a82400&#8243; url=\u00bbwww.youtube.com\/@sergiohijanolopez\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb30px\u00bb]youtube[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alguien dijo alguna vez: \u201cLo m\u00e1s valioso de la vida no es lo que tenemos, sino a quien tenemos\u201d. El pasado 26 y 27 de octubre y 02 de noviembre, contamos con la colaboraci\u00f3n de la Asociaci\u00f3n AESLEME bajo la representaci\u00f3n de Sergio Hijano para ofrecernos unas charlas formativas para la sensibilizaci\u00f3n para la Prevenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":89288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[126],"tags":[],"class_list":["post-89293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Alguien dijo alguna vez: \u201cLo m\u00e1s valioso de la vida no es lo que tenemos, sino a quien tenemos\u201d. El pasado 26 y 27 de octubre y 02 de noviembre, contamos con la colaboraci\u00f3n de la Asociaci\u00f3n AESLEME bajo la representaci\u00f3n de Sergio Hijano para ofrecernos unas charlas formativas para la sensibilizaci\u00f3n para la Prevenci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-17T09:10:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-17T09:16:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/11\/1700062604096-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n MLG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n MLG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n MLG\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\"},\"headline\":\"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico\",\"datePublished\":\"2023-11-17T09:10:37+00:00\",\"dateModified\":\"2023-11-17T09:16:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/\"},\"wordCount\":778,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/11\\\/1700062604096-scaled.jpg\",\"articleSection\":[\"Casa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/\",\"name\":\"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/11\\\/1700062604096-scaled.jpg\",\"datePublished\":\"2023-11-17T09:10:37+00:00\",\"dateModified\":\"2023-11-17T09:16:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/11\\\/1700062604096-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/11\\\/1700062604096-scaled.jpg\",\"width\":2560,\"height\":1183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"description\":\"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.\",\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\",\"name\":\"Salesianos M\u00e1laga\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"width\":1937,\"height\":1490,\"caption\":\"Salesianos M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\",\"name\":\"Comunicaci\u00f3n MLG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n MLG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","og_description":"Alguien dijo alguna vez: \u201cLo m\u00e1s valioso de la vida no es lo que tenemos, sino a quien tenemos\u201d. El pasado 26 y 27 de octubre y 02 de noviembre, contamos con la colaboraci\u00f3n de la Asociaci\u00f3n AESLEME bajo la representaci\u00f3n de Sergio Hijano para ofrecernos unas charlas formativas para la sensibilizaci\u00f3n para la Prevenci\u00f3n [&hellip;]","og_url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/","og_site_name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","article_published_time":"2023-11-17T09:10:37+00:00","article_modified_time":"2023-11-17T09:16:29+00:00","og_image":[{"width":2560,"height":1183,"url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/11\/1700062604096-scaled.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n MLG","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3n MLG","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/"},"author":{"name":"Comunicaci\u00f3n MLG","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b"},"headline":"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico","datePublished":"2023-11-17T09:10:37+00:00","dateModified":"2023-11-17T09:16:29+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/"},"wordCount":778,"commentCount":0,"publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/11\/1700062604096-scaled.jpg","articleSection":["Casa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/","name":"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/11\/1700062604096-scaled.jpg","datePublished":"2023-11-17T09:10:37+00:00","dateModified":"2023-11-17T09:16:29+00:00","breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/11\/1700062604096-scaled.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/11\/1700062604096-scaled.jpg","width":2560,"height":1183},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nada-vale-mas-que-una-vida-formacion-para-la-prevencion-de-accidentes-de-trafico-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"\u201cNada vale m\u00e1s que una vida\u00bb Formaci\u00f3n para la Prevenci\u00f3n de Accidentes de Tr\u00e1fico"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website","url":"https:\/\/malaga.salesianos.edu\/colegio\/","name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","description":"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.","publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization","name":"Salesianos M\u00e1laga","url":"https:\/\/malaga.salesianos.edu\/colegio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","width":1937,"height":1490,"caption":"Salesianos M\u00e1laga"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b","name":"Comunicaci\u00f3n MLG","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n MLG"}}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/89293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=89293"}],"version-history":[{"count":7,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/89293\/revisions"}],"predecessor-version":[{"id":89330,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/89293\/revisions\/89330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/89288"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=89293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=89293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=89293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}