{"id":89240,"date":"2023-10-29T16:59:34","date_gmt":"2023-10-29T15:57:06","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/"},"modified":"2023-10-29T16:59:50","modified_gmt":"2023-10-29T15:59:50","slug":"formacion-de-profesorado-de-nueva-incorporacion","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/","title":{"rendered":"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; text_orientation=\u00bbjustified\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">El pasado martes 24 de octubre tuvo lugar una formaci\u00f3n para los nuevos profesores y profesoras que han pasado a formar parte del equipo educativo en los \u00faltimos a\u00f1os. Este tipo de encuentros sirve como acompa\u00f1amiento para estos nuevos docentes y permite optimizar la transferencia de la identidad del centro, tan importante para formar educadores salesianos, personas comprometidas que educan desde el coraz\u00f3n con un sello propio y distintivo, con la misi\u00f3n de ayudar al alumnado a sacar la mejor versi\u00f3n de ellos mismos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La jornada comenz\u00f3 con una merienda en un momento distendido para compartir. Continu\u00f3 con una serie de din\u00e1micas activas en la que los nuevos docentes profundizaron su conocimiento sobre algunas figuras Salesianas de importante relevancia, especialmente para la Casa de M\u00e1laga como Bartolom\u00e9 Galleri, Juan Cagliero y Eduardo Dom\u00ednguez \u00c1vila. El encuentro concluy\u00f3 con un momento de reflexi\u00f3n com\u00fan en el que se compartieron distintos testimonios que aportaron conocimiento, experiencia y motivaci\u00f3n. \u201cComo educadores salesianos, se debe actuar de la manera que somos\u201d.\u00a0<\/span><\/p>\n<p>[\/et_pb_text][et_pb_gallery _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; gallery_ids=\u00bb81443,81442,81441,81440,81439,81438,81436,81435,81434,81433,81421,81423,81425,81426,81427,81428,81429,81430,81431,81432,81420,81419&#8243; show_title_and_caption=\u00bboff\u00bb posts_number=\u00bb8&#8243;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado martes 24 de octubre tuvo lugar una formaci\u00f3n para los nuevos profesores y profesoras que han pasado a formar parte del equipo educativo en los \u00faltimos a\u00f1os. Este tipo de encuentros sirve como acompa\u00f1amiento para estos nuevos docentes y permite optimizar la transferencia de la identidad del centro, tan importante para formar educadores [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":89241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[126],"tags":[],"class_list":["post-89240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"El pasado martes 24 de octubre tuvo lugar una formaci\u00f3n para los nuevos profesores y profesoras que han pasado a formar parte del equipo educativo en los \u00faltimos a\u00f1os. Este tipo de encuentros sirve como acompa\u00f1amiento para estos nuevos docentes y permite optimizar la transferencia de la identidad del centro, tan importante para formar educadores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-29T15:57:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-29T15:59:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/10\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n MLG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n MLG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n MLG\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\"},\"headline\":\"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n\",\"datePublished\":\"2023-10-29T15:57:06+00:00\",\"dateModified\":\"2023-10-29T15:59:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/\"},\"wordCount\":285,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg\",\"articleSection\":[\"Casa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/\",\"name\":\"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg\",\"datePublished\":\"2023-10-29T15:57:06+00:00\",\"dateModified\":\"2023-10-29T15:59:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/formacion-de-profesorado-de-nueva-incorporacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"description\":\"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.\",\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\",\"name\":\"Salesianos M\u00e1laga\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"width\":1937,\"height\":1490,\"caption\":\"Salesianos M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\",\"name\":\"Comunicaci\u00f3n MLG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n MLG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/","og_locale":"es_ES","og_type":"article","og_title":"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","og_description":"El pasado martes 24 de octubre tuvo lugar una formaci\u00f3n para los nuevos profesores y profesoras que han pasado a formar parte del equipo educativo en los \u00faltimos a\u00f1os. Este tipo de encuentros sirve como acompa\u00f1amiento para estos nuevos docentes y permite optimizar la transferencia de la identidad del centro, tan importante para formar educadores [&hellip;]","og_url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/","og_site_name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","article_published_time":"2023-10-29T15:57:06+00:00","article_modified_time":"2023-10-29T15:59:50+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/10\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n MLG","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3n MLG","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/"},"author":{"name":"Comunicaci\u00f3n MLG","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b"},"headline":"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n","datePublished":"2023-10-29T15:57:06+00:00","dateModified":"2023-10-29T15:59:50+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/"},"wordCount":285,"commentCount":0,"publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/10\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg","articleSection":["Casa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/","name":"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/10\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg","datePublished":"2023-10-29T15:57:06+00:00","dateModified":"2023-10-29T15:59:50+00:00","breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/10\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/10\/a64f6ab9-b4f0-4921-bd07-0dfc385e6619.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/formacion-de-profesorado-de-nueva-incorporacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n de Profesorado de Nueva Incorporaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website","url":"https:\/\/malaga.salesianos.edu\/colegio\/","name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","description":"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.","publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization","name":"Salesianos M\u00e1laga","url":"https:\/\/malaga.salesianos.edu\/colegio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","width":1937,"height":1490,"caption":"Salesianos M\u00e1laga"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b","name":"Comunicaci\u00f3n MLG","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n MLG"}}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/89240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=89240"}],"version-history":[{"count":4,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/89240\/revisions"}],"predecessor-version":[{"id":89246,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/89240\/revisions\/89246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/89241"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=89240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=89240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=89240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}