{"id":23255,"date":"2022-04-22T20:00:44","date_gmt":"2022-04-22T18:00:44","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/"},"modified":"2022-04-22T20:00:44","modified_gmt":"2022-04-22T18:00:44","slug":"feliz-dia-del-libro","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/","title":{"rendered":"\u00a1Feliz d\u00eda del libro!"},"content":{"rendered":"<p>Hoy Infantil y Primaria ha celebrado el d\u00eda del libro en el colegio. Hemos podido ver entusiasmo en las diferentes etapas desde los m\u00e1s peque\u00f1itos de infantil hasta los mayores de Primaria.<\/p>\n<p>En Educaci\u00f3n Infantil hemos contado con la ayuda de algunas madres que nos han visitado para contarnos un cuento. Desde aqu\u00ed os queremos dar las gracias por vuestra participaci\u00f3n en un d\u00eda tan divertido como ha sido el de hoy. Adem\u00e1s, todos los ni\u00f1os de la etapa de Infantil se han tra\u00eddo un coj\u00edn y un cuento para hacer una lectura en el patio del colegio bajo el lema de \u201cAl aire libro\u201d. Durante esta lectura han podido disfrutar de los cuentos que se han tra\u00eddo y de los cuentos de sus compa\u00f1eros. Lo hemos pasado en grande.<\/p>\n<p>Por otra parte, la etapa de Educaci\u00f3n Primaria ha realizado diferentes actividades. En el primer ciclo de la etapa han realizado una actividad en la que han estado leyendo ellos mismo las lecturas que m\u00e1s les apasiona.<\/p>\n<p>En el segundo ciclo de Primaria han trabajado el d\u00eda del libro realizando un bingo literario, a trav\u00e9s del cual han estado preparando frases para motivar a la lectura. Desde luego, estos chicos de Primaria son unos apasionados de las historias por contar.<\/p>\n<p>Los mayores de Primaria, el tercer ciclo, se ha llevado a cabo una lectura colectiva en la que los alumnos y alumnas han ido saliendo a un atril leyendo un libro elegido por ellos mismos. Tambi\u00e9n han realizado un decorado en clase con la tem\u00e1tica del d\u00eda del libro. \u00a1Nos encanta leer!<\/p>\n<div class=\"et_pb_slider et_pb_slider_fullwidth_off et_pb_gallery_post_type\">\n\t\t\t\t<div class=\"et_pb_slides\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hoy Infantil y Primaria ha celebrado el d\u00eda del libro en el colegio. Hemos podido ver entusiasmo en las diferentes etapas desde los m\u00e1s peque\u00f1itos de infantil hasta los mayores de Primaria. En Educaci\u00f3n Infantil hemos contado con la ayuda de algunas madres que nos han visitado para contarnos un cuento. Desde aqu\u00ed os queremos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[126,10,18,20],"tags":[],"class_list":["post-23255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-colegio","category-infantil","category-primaria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Feliz d\u00eda del libro! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Feliz d\u00eda del libro! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Hoy Infantil y Primaria ha celebrado el d\u00eda del libro en el colegio. Hemos podido ver entusiasmo en las diferentes etapas desde los m\u00e1s peque\u00f1itos de infantil hasta los mayores de Primaria. En Educaci\u00f3n Infantil hemos contado con la ayuda de algunas madres que nos han visitado para contarnos un cuento. Desde aqu\u00ed os queremos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-22T18:00:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/04\/PHOTO-2022-04-22-14-08-46-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"2016\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n MLG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n MLG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n MLG\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\"},\"headline\":\"\u00a1Feliz d\u00eda del libro!\",\"datePublished\":\"2022-04-22T18:00:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/PHOTO-2022-04-22-14-08-46-2.jpg\",\"articleSection\":[\"Casa\",\"Colegio\",\"Infantil\",\"Primaria\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/\",\"name\":\"\u00a1Feliz d\u00eda del libro! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/PHOTO-2022-04-22-14-08-46-2.jpg\",\"datePublished\":\"2022-04-22T18:00:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/PHOTO-2022-04-22-14-08-46-2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/PHOTO-2022-04-22-14-08-46-2.jpg\",\"width\":980,\"height\":2016},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/feliz-dia-del-libro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Feliz d\u00eda del libro!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"description\":\"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.\",\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\",\"name\":\"Salesianos M\u00e1laga\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"width\":1937,\"height\":1490,\"caption\":\"Salesianos M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\",\"name\":\"Comunicaci\u00f3n MLG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n MLG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Feliz d\u00eda del libro! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Feliz d\u00eda del libro! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","og_description":"Hoy Infantil y Primaria ha celebrado el d\u00eda del libro en el colegio. Hemos podido ver entusiasmo en las diferentes etapas desde los m\u00e1s peque\u00f1itos de infantil hasta los mayores de Primaria. En Educaci\u00f3n Infantil hemos contado con la ayuda de algunas madres que nos han visitado para contarnos un cuento. Desde aqu\u00ed os queremos [&hellip;]","og_url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/","og_site_name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","article_published_time":"2022-04-22T18:00:44+00:00","og_image":[{"width":980,"height":2016,"url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/04\/PHOTO-2022-04-22-14-08-46-2.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n MLG","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3n MLG","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/"},"author":{"name":"Comunicaci\u00f3n MLG","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b"},"headline":"\u00a1Feliz d\u00eda del libro!","datePublished":"2022-04-22T18:00:44+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/04\/PHOTO-2022-04-22-14-08-46-2.jpg","articleSection":["Casa","Colegio","Infantil","Primaria"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/","name":"\u00a1Feliz d\u00eda del libro! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/04\/PHOTO-2022-04-22-14-08-46-2.jpg","datePublished":"2022-04-22T18:00:44+00:00","breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/04\/PHOTO-2022-04-22-14-08-46-2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/04\/PHOTO-2022-04-22-14-08-46-2.jpg","width":980,"height":2016},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/feliz-dia-del-libro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"\u00a1Feliz d\u00eda del libro!"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website","url":"https:\/\/malaga.salesianos.edu\/colegio\/","name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","description":"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.","publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization","name":"Salesianos M\u00e1laga","url":"https:\/\/malaga.salesianos.edu\/colegio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","width":1937,"height":1490,"caption":"Salesianos M\u00e1laga"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b","name":"Comunicaci\u00f3n MLG","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n MLG"}}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/23255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=23255"}],"version-history":[{"count":0,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/23255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/23256"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=23255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=23255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=23255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}