{"id":22754,"date":"2021-12-06T11:24:46","date_gmt":"2021-12-06T10:24:46","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/"},"modified":"2022-02-08T21:49:37","modified_gmt":"2022-02-08T20:49:37","slug":"dia-de-la-constitucion","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/","title":{"rendered":"\u00a1Feliz d\u00eda de la Constituci\u00f3n!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Hoy celebramos el d\u00eda de la Constituci\u00f3n Espa\u00f1ola, es por ello que a lo largo de la pasada semana, realizamos una gran cantidad de actividades para conmemorar este d\u00eda y para que los chicos y chicas conozcan la relevancia de dicho texto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De esta forma, se desarrollaron actividades de todo tipo: investigaciones, elaboraci\u00f3n de caligramas, lapbooks, Kahoot, libro con los derechos recogidos en la Constituci\u00f3n, lecturas, sopa de letras, datos y banderas sobre las distintas comunidades aut\u00f3nomas que integran Espa\u00f1a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gracias a todo ello, los\/as alumnos\/as han comprendido el porqu\u00e9 de la celebraci\u00f3n del D\u00eda de la Constituci\u00f3n y su enorme importancia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a1Feliz d\u00eda de la Constituci\u00f3n a todos y a todas!<\/span><\/p>\n<div class=\"et_pb_slider et_pb_slider_fullwidth_off et_pb_gallery_post_type\">\n\t\t\t\t<div class=\"et_pb_slides\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hoy celebramos el d\u00eda de la Constituci\u00f3n Espa\u00f1ola, es por ello que a lo largo de la pasada semana, realizamos una gran cantidad de actividades para conmemorar este d\u00eda y para que los chicos y chicas conozcan la relevancia de dicho texto. De esta forma, se desarrollaron actividades de todo tipo: investigaciones, elaboraci\u00f3n de caligramas, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[126,10,20],"tags":[],"class_list":["post-22754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-colegio","category-primaria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Feliz d\u00eda de la Constituci\u00f3n! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Feliz d\u00eda de la Constituci\u00f3n! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Hoy celebramos el d\u00eda de la Constituci\u00f3n Espa\u00f1ola, es por ello que a lo largo de la pasada semana, realizamos una gran cantidad de actividades para conmemorar este d\u00eda y para que los chicos y chicas conozcan la relevancia de dicho texto. De esta forma, se desarrollaron actividades de todo tipo: investigaciones, elaboraci\u00f3n de caligramas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-06T10:24:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-08T20:49:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/02\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1302\" \/>\n\t<meta property=\"og:image:height\" content=\"1098\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3n MLG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3n MLG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3n MLG\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\"},\"headline\":\"\u00a1Feliz d\u00eda de la Constituci\u00f3n!\",\"datePublished\":\"2021-12-06T10:24:46+00:00\",\"dateModified\":\"2022-02-08T20:49:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg\",\"articleSection\":[\"Casa\",\"Colegio\",\"Primaria\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/\",\"name\":\"\u00a1Feliz d\u00eda de la Constituci\u00f3n! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg\",\"datePublished\":\"2021-12-06T10:24:46+00:00\",\"dateModified\":\"2022-02-08T20:49:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg\",\"width\":1302,\"height\":1098},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/dia-de-la-constitucion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Feliz d\u00eda de la Constituci\u00f3n!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"description\":\"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.\",\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\",\"name\":\"Salesianos M\u00e1laga\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"width\":1937,\"height\":1490,\"caption\":\"Salesianos M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/fd7e7b338b40e1c817a659fe5fce718b\",\"name\":\"Comunicaci\u00f3n MLG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3n MLG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Feliz d\u00eda de la Constituci\u00f3n! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Feliz d\u00eda de la Constituci\u00f3n! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","og_description":"Hoy celebramos el d\u00eda de la Constituci\u00f3n Espa\u00f1ola, es por ello que a lo largo de la pasada semana, realizamos una gran cantidad de actividades para conmemorar este d\u00eda y para que los chicos y chicas conozcan la relevancia de dicho texto. De esta forma, se desarrollaron actividades de todo tipo: investigaciones, elaboraci\u00f3n de caligramas, [&hellip;]","og_url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/","og_site_name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","article_published_time":"2021-12-06T10:24:46+00:00","article_modified_time":"2022-02-08T20:49:37+00:00","og_image":[{"width":1302,"height":1098,"url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/02\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3n MLG","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3n MLG","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/"},"author":{"name":"Comunicaci\u00f3n MLG","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b"},"headline":"\u00a1Feliz d\u00eda de la Constituci\u00f3n!","datePublished":"2021-12-06T10:24:46+00:00","dateModified":"2022-02-08T20:49:37+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/02\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg","articleSection":["Casa","Colegio","Primaria"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/","name":"\u00a1Feliz d\u00eda de la Constituci\u00f3n! - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/02\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg","datePublished":"2021-12-06T10:24:46+00:00","dateModified":"2022-02-08T20:49:37+00:00","breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/02\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/02\/Captura-de-pantalla-2021-12-06-a-las-10.11.43-2.jpg","width":1302,"height":1098},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/dia-de-la-constitucion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"\u00a1Feliz d\u00eda de la Constituci\u00f3n!"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website","url":"https:\/\/malaga.salesianos.edu\/colegio\/","name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","description":"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.","publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization","name":"Salesianos M\u00e1laga","url":"https:\/\/malaga.salesianos.edu\/colegio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","width":1937,"height":1490,"caption":"Salesianos M\u00e1laga"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/person\/fd7e7b338b40e1c817a659fe5fce718b","name":"Comunicaci\u00f3n MLG","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ce5c66be6c7ab6b098b2ac29099a68d1cdb824afbb8aadf744614ce719778ff?s=96&d=mm&r=g","caption":"Comunicaci\u00f3n MLG"}}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=22754"}],"version-history":[{"count":2,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22754\/revisions"}],"predecessor-version":[{"id":22813,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22754\/revisions\/22813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/22755"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=22754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=22754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=22754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}