{"id":19598,"date":"2019-12-04T15:56:02","date_gmt":"2019-12-04T09:11:38","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/"},"modified":"2019-12-04T15:56:03","modified_gmt":"2019-12-04T14:56:03","slug":"nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/","title":{"rendered":"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb3.22.3&#8243; custom_padding=\u00bb2px|0px|54px|0px\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb3.25&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbDesarrollo\u00bb _builder_version=\u00bb4.0.6&#8243; text_orientation=\u00bbjustified\u00bb z_index_tablet=\u00bb500&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p><em><strong>Con motivo del 25N, d\u00eda internacional de la eliminaci\u00f3n de la violencia contra la mujer, nuestro alumnado de FPB, quiso contribuir con un v\u00eddeo a visibilizar la violencia de g\u00e9nero entre adolescentes.<\/strong><\/em><\/p>\n<p>\u00abTen\u00eda los nudillos de la mano derecha destrozados y\u00a0<b>empez\u00f3 a restregarme su sangre por la cara mientras me gritaba que la pr\u00f3xima vez iba a ser la m\u00eda<\/b>. Cuando llegu\u00e9 a casa me invent\u00e9 que hab\u00eda sangrado por la nariz\u00bb.\u00a0<b>Sheila<\/b>\u00a0ten\u00eda\u00a0<b>15 a\u00f1os<\/b>\u00a0la primera vez que lo vio; \u00e9l, 17.<\/p>\n<p>Casi\u00a0<b>el 11% de las v\u00edctimas de violencia de g\u00e9nero en Espa\u00f1a son menores de 18 a\u00f1os<\/b>, y la cosa va en aumento.\u00a0 Desde 2009,\u00a0<a href=\"https:\/\/objetivo.anar.org\/estudio\/\">la fundaci\u00f3n ANAR<\/a>\u00a0detect\u00f3\u00a0<b>un aumento del 682%<\/b>\u00a0en los casos de violencia de g\u00e9nero entre menores de edad.<\/p>\n<p>La violencia de g\u00e9nero entre adolescentes tiene tres elementos particulares. Hay una parte de\u00a0<b>violencia de control muy potente<\/b>\u00a0y un elemento, que es la\u00a0<b>tecnolog\u00eda<\/b>\u00a0y lo digital, que no se daba antes y tampoco se identifica de forma tan evidente en mujeres adultas.<\/p>\n<p>El tercer elemento es el elevado grado de\u00a0<b>violencia sexual<\/b>: las llamadas pruebas de amor -\u00abSi no te acuestas conmigo es porque no me quieres\u00bb. Ellas acceden a peticiones que muchas veces no desean. Lo hacen porque creen que, si se niegan, ellos romper\u00e1n la relaci\u00f3n.<\/p>\n<p>La\u00a0<b>hipersexualizaci\u00f3n<\/b>, el consumo precoz de\u00a0<b>pornograf\u00eda\u00a0<\/b>y la falta de\u00a0<b>educaci\u00f3n sexual<\/b>\u00a0constituyen los pilares de estas actitudes, que se agravan con una socializaci\u00f3n basada en el g\u00e9nero. \u00abA nosotras nos educan en la cultura del agrado, a ellos en el poder, la fuerza y la dominaci\u00f3n; a nosotras se nos penaliza si tenemos sexo o mucho sexo; a ellos, en cambio, se les condena si no lo tienen\u00bb, a\u00f1ade la experta de Mujeres en Igualdad.<\/p>\n<p>Con motivo del 25N, nuestro alumnado de FPB, quiso contribuir con un v\u00eddeo a visibilizar la violencia de g\u00e9nero entre adolescentes. Bas\u00e1ndose en la canci\u00f3n \u201cla puerta violeta\u201d de la cantante Rozal\u00e9n\u00a0 crearon sus puertas, con mensajes propios, denunciando la violencia contra las mujeres y las v\u00edctimas que se producen cada a\u00f1o por este motivo.<\/p>\n<p>[\/et_pb_text][et_pb_video src=\u00bbhttps:\/\/youtu.be\/PsB7ZPBCqss\u00bb _builder_version=\u00bb4.0.6&#8243; z_index_tablet=\u00bb500&#8243;][\/et_pb_video][et_pb_gallery gallery_ids=\u00bb19566,19565,19564,19563&#8243; gallery_orderby=\u00bbrand\u00bb posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb _builder_version=\u00bb4.0.6&#8243; z_index_tablet=\u00bb500&#8243; hover_enabled=\u00bb0&#8243;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo del 25N, d\u00eda internacional de la eliminaci\u00f3n de la violencia contra la mujer, nuestro alumnado de FPB, quiso contribuir con un v\u00eddeo a visibilizar la violencia de g\u00e9nero entre adolescentes. \u00abTen\u00eda los nudillos de la mano derecha destrozados y\u00a0empez\u00f3 a restregarme su sangre por la cara mientras me gritaba que la pr\u00f3xima vez [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":19603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[126,15],"tags":[],"class_list":["post-19598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-fpb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Con motivo del 25N, d\u00eda internacional de la eliminaci\u00f3n de la violencia contra la mujer, nuestro alumnado de FPB, quiso contribuir con un v\u00eddeo a visibilizar la violencia de g\u00e9nero entre adolescentes. &quot;Ten\u00eda los nudillos de la mano derecha destrozados y\u00a0empez\u00f3 a restregarme su sangre por la cara mientras me gritaba que la pr\u00f3xima vez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-04T09:11:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-04T14:56:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2019\/12\/IMG-20191202-WA0006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero\",\"datePublished\":\"2019-12-04T09:11:38+00:00\",\"dateModified\":\"2019-12-04T14:56:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/\"},\"wordCount\":515,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/IMG-20191202-WA0006.jpg\",\"articleSection\":[\"Casa\",\"FPB\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/\",\"name\":\"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/IMG-20191202-WA0006.jpg\",\"datePublished\":\"2019-12-04T09:11:38+00:00\",\"dateModified\":\"2019-12-04T14:56:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/IMG-20191202-WA0006.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/IMG-20191202-WA0006.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"description\":\"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.\",\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\",\"name\":\"Salesianos M\u00e1laga\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"width\":1937,\"height\":1490,\"caption\":\"Salesianos M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/","og_locale":"es_ES","og_type":"article","og_title":"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","og_description":"Con motivo del 25N, d\u00eda internacional de la eliminaci\u00f3n de la violencia contra la mujer, nuestro alumnado de FPB, quiso contribuir con un v\u00eddeo a visibilizar la violencia de g\u00e9nero entre adolescentes. \"Ten\u00eda los nudillos de la mano derecha destrozados y\u00a0empez\u00f3 a restregarme su sangre por la cara mientras me gritaba que la pr\u00f3xima vez [&hellip;]","og_url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/","og_site_name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","article_published_time":"2019-12-04T09:11:38+00:00","article_modified_time":"2019-12-04T14:56:03+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2019\/12\/IMG-20191202-WA0006.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/"},"author":{"name":"","@id":""},"headline":"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero","datePublished":"2019-12-04T09:11:38+00:00","dateModified":"2019-12-04T14:56:03+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/"},"wordCount":515,"commentCount":0,"publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2019\/12\/IMG-20191202-WA0006.jpg","articleSection":["Casa","FPB"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/","name":"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2019\/12\/IMG-20191202-WA0006.jpg","datePublished":"2019-12-04T09:11:38+00:00","dateModified":"2019-12-04T14:56:03+00:00","breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2019\/12\/IMG-20191202-WA0006.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2019\/12\/IMG-20191202-WA0006.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/nuestro-alumnado-de-fpb-reflexiona-sobre-la-violencia-de-genero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Nuestro alumnado de FPB reflexiona sobre la violencia de g\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website","url":"https:\/\/malaga.salesianos.edu\/colegio\/","name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","description":"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.","publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization","name":"Salesianos M\u00e1laga","url":"https:\/\/malaga.salesianos.edu\/colegio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","width":1937,"height":1490,"caption":"Salesianos M\u00e1laga"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/19598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=19598"}],"version-history":[{"count":5,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/19598\/revisions"}],"predecessor-version":[{"id":19604,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/19598\/revisions\/19604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/19603"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=19598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=19598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=19598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}