{"id":14685,"date":"2018-10-03T13:45:11","date_gmt":"2018-10-03T11:45:11","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/"},"modified":"2018-10-05T01:41:11","modified_gmt":"2018-10-04T23:41:11","slug":"salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/","title":{"rendered":"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual"},"content":{"rendered":"<p>[et_pb_section bb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb custom_padding=\u00bb2px|0px|54px|0px\u00bb][et_pb_row admin_label=\u00bbrow\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_size=\u00bbinitial\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text admin_label=\u00bbEntradilla\u00bb text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.15&#8243;]<\/p>\n<p><em><b>Segundo d\u00eda del IV Foro ALIANZA PARA LA FP Dual, donde hemos recibido el reconocimiento por la colaboraci\u00f3n de nuestro centro con la fundaci\u00f3n Bertelsmann.<\/b><\/em><\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.15&#8243;]<\/p>\n<p style=\"font-weight: 400;\">Tres de nuestros profesores participan en el <strong>IV Foro ALIANZA PARA LA FP Dual<\/strong> donde, adem\u00e1s de compartir y aprender sobre la FP Dual en Espa\u00f1a y fuera de nuestras fronteras, D. Francisco Salado, Vicepresidente Primero de la diputaci\u00f3n de M\u00e1laga, nos ha nombrado como uno de los centros a valorar desde el punto de vista de FP Dual.<\/p>\n<p style=\"font-weight: 400;\">Adem\u00e1s, hemos recibido el reconocimiento por la colaboraci\u00f3n de nuestro centro con la <a href=\"https:\/\/www.fundacionbertelsmann.org\/es\/home\/\"><strong>Fundaci\u00f3n Bertelsmann,<\/strong><\/a>\u00a0la cual apoya la FP Dual y lleva m\u00e1s de 23 a\u00f1os trabajando \u2018<a class=\"internal-link\" href=\"https:\/\/www.fundacionbertelsmann.org\/es\/home\/empleo-juvenil\/\">Por el Empleo Juvenil<\/a>\u2019.<\/p>\n<p style=\"font-weight: 400;\">Dos d\u00edas muy intensos y gratificantes para nuestro Colegio Salesiano San Bartolom\u00e9 de M\u00e1laga, uno de los centros pioneros de la FP Dual en Andaluc\u00eda.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbT\u00edtulo Galer\u00eda\u00bb _builder_version=\u00bb3.10&#8243;]<\/p>\n<blockquote>\n<h3><strong>Galer\u00eda de fotos:<\/strong><\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb14761,14760,14759,14758,14757,14756&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#d12525&#8243; hover_overlay_color=\u00bbrgba(255,255,255,0.9)\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.15&#8243; gallery_orderby=\u00bbrand\u00bb \/][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo d\u00eda del IV Foro ALIANZA PARA LA FP Dual, donde hemos recibido el reconocimiento por la colaboraci\u00f3n con la fundaci\u00f3n Bertelsmann.<\/p>\n","protected":false},"author":40,"featured_media":14686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8,10],"tags":[],"class_list":["post-14685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciclos-formativos","category-colegio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Segundo d\u00eda del IV Foro ALIANZA PARA LA FP Dual, donde hemos recibido el reconocimiento por la colaboraci\u00f3n con la fundaci\u00f3n Bertelsmann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-03T11:45:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-04T23:41:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/10\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual\",\"datePublished\":\"2018-10-03T11:45:11+00:00\",\"dateModified\":\"2018-10-04T23:41:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg\",\"articleSection\":[\"Ciclos Formativos\",\"Colegio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/\",\"name\":\"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg\",\"datePublished\":\"2018-10-03T11:45:11+00:00\",\"dateModified\":\"2018-10-04T23:41:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg\",\"width\":1600,\"height\":898},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"description\":\"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.\",\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\",\"name\":\"Salesianos M\u00e1laga\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"width\":1937,\"height\":1490,\"caption\":\"Salesianos M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/","og_locale":"es_ES","og_type":"article","og_title":"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","og_description":"Segundo d\u00eda del IV Foro ALIANZA PARA LA FP Dual, donde hemos recibido el reconocimiento por la colaboraci\u00f3n con la fundaci\u00f3n Bertelsmann.","og_url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/","og_site_name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","article_published_time":"2018-10-03T11:45:11+00:00","article_modified_time":"2018-10-04T23:41:11+00:00","og_image":[{"width":1600,"height":898,"url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/10\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/"},"author":{"name":"","@id":""},"headline":"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual","datePublished":"2018-10-03T11:45:11+00:00","dateModified":"2018-10-04T23:41:11+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/10\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg","articleSection":["Ciclos Formativos","Colegio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/","name":"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/10\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg","datePublished":"2018-10-03T11:45:11+00:00","dateModified":"2018-10-04T23:41:11+00:00","breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/10\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/10\/WhatsApp-Image-2018-10-03-at-09.32.37.jpeg","width":1600,"height":898},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/salesianos-malaga-participa-en-el-iv-foro-alianza-para-la-fp-dual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Salesianos M\u00e1laga participa en el IV Foro Alianza para la FP Dual"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website","url":"https:\/\/malaga.salesianos.edu\/colegio\/","name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","description":"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.","publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization","name":"Salesianos M\u00e1laga","url":"https:\/\/malaga.salesianos.edu\/colegio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","width":1937,"height":1490,"caption":"Salesianos M\u00e1laga"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=14685"}],"version-history":[{"count":3,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14685\/revisions"}],"predecessor-version":[{"id":14792,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14685\/revisions\/14792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/14686"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=14685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=14685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=14685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}