{"id":11948,"date":"2018-06-04T20:14:06","date_gmt":"2018-06-04T18:14:06","guid":{"rendered":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/"},"modified":"2018-06-04T20:36:07","modified_gmt":"2018-06-04T18:36:07","slug":"asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso","status":"publish","type":"post","link":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/","title":{"rendered":"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso"},"content":{"rendered":"<p>[et_pb_section bb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb custom_padding=\u00bb2px|0px|54px|0px\u00bb][et_pb_row admin_label=\u00bbrow\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text admin_label=\u00bbEntradilla\u00bb text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.4.1&#8243;]<\/p>\n<p><em><strong>El pasado s\u00e1bado d\u00eda 2 de junio se celebr\u00f3 la Asamblea General Ordinaria de los socios del AMPA. En ella se inform\u00f3 a los socios de las actividades realizadas durante el curso.<\/strong><\/em><\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.4.1&#8243;]<\/p>\n<p>Se present\u00f3 el informe de cuentas, escuchamos las ideas y sugerencias de los socios, y debatimos sobre diversos temas de inter\u00e9s para los padres. Contamos con la presencia de D. Antonio Gil Prieto y D. Juan Baena, que adelantaron algunas actividades e informaciones de inter\u00e9s para el pr\u00f3ximo a\u00f1o.<\/p>\n<p>Al finalizar la Asamblea nos reunimos para compartir una jornada de convivencia, que gust\u00f3 mucho a todos, ya que se vivi\u00f3 en un ambiente familiar.<\/p>\n<p>Se llev\u00f3 a cabo el concurso de postres, que fue un momento muy divertido, en el que la familia Rueda Cruces fue elegida como la ganadora del premio al mejor postre.<\/p>\n<p>Tambi\u00e9n tuvimos un momento de agradecimiento para D. Joaqu\u00edn Mart\u00edn por la extraordinaria labor que realiza con nosotros, y sin la cual no podr\u00edamos llevar a cabo las jornadas de formaci\u00f3n que llamamos \u00abTaller de Padres\u00bb.<\/p>\n<p>En definitiva, una experiencia que nos gustar\u00eda repetir el pr\u00f3ximo a\u00f1o.<\/p>\n<p>Nuestro m\u00e1s sincero agradecimiento a Yolanda Prada, Salesiana Cooperadora de esta casa que se encarg\u00f3 de realizar el arroz que tanto gust\u00f3 a todo el mundo.<\/p>\n<p>Gracias tambi\u00e9n a todos los socios por hacer que con su asistencia, esta celebraci\u00f3n fuera un \u00e9xito.<\/p>\n<blockquote>\n<h3><strong>Galer\u00eda de fotos:<\/strong><\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb14011,14012,14013,14014,14015,14016,14017,14018,14019&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#d12525&#8243; hover_overlay_color=\u00bbrgba(255,255,255,0.9)\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.4.1&#8243; gallery_orderby=\u00bbrand\u00bb \/][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado d\u00eda 2 de junio se celebr\u00f3 la Asamblea General Ordinaria de los socios del AMPA. En ella se inform\u00f3 a los socios de las actividades realizadas durante el curso.<\/p>\n","protected":false},"author":19,"featured_media":11949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[123,10],"tags":[191],"class_list":["post-11948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asoc-madres-y-padres-de-alumnos","category-colegio","tag-asambleas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"El pasado s\u00e1bado d\u00eda 2 de junio se celebr\u00f3 la Asamblea General Ordinaria de los socios del AMPA. En ella se inform\u00f3 a los socios de las actividades realizadas durante el curso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-04T18:14:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-04T18:36:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/06\/Asamblea_AMPA_junio_2018_9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"925\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso\",\"datePublished\":\"2018-06-04T18:14:06+00:00\",\"dateModified\":\"2018-06-04T18:36:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/06\\\/Asamblea_AMPA_junio_2018_9.jpg\",\"keywords\":[\"Asambleas\"],\"articleSection\":[\"AMPA\",\"Colegio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/\",\"name\":\"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/06\\\/Asamblea_AMPA_junio_2018_9.jpg\",\"datePublished\":\"2018-06-04T18:14:06+00:00\",\"dateModified\":\"2018-06-04T18:36:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/06\\\/Asamblea_AMPA_junio_2018_9.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/06\\\/Asamblea_AMPA_junio_2018_9.jpg\",\"width\":925,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/blog\\\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga\",\"description\":\"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.\",\"publisher\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#organization\",\"name\":\"Salesianos M\u00e1laga\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"contentUrl\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/MALAGAobraVN2.jpg\",\"width\":1937,\"height\":1490,\"caption\":\"Salesianos M\u00e1laga\"},\"image\":{\"@id\":\"https:\\\/\\\/malaga.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/","og_locale":"es_ES","og_type":"article","og_title":"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","og_description":"El pasado s\u00e1bado d\u00eda 2 de junio se celebr\u00f3 la Asamblea General Ordinaria de los socios del AMPA. En ella se inform\u00f3 a los socios de las actividades realizadas durante el curso.","og_url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/","og_site_name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","article_published_time":"2018-06-04T18:14:06+00:00","article_modified_time":"2018-06-04T18:36:07+00:00","og_image":[{"width":925,"height":720,"url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/06\/Asamblea_AMPA_junio_2018_9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/#article","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/"},"author":{"name":"","@id":""},"headline":"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso","datePublished":"2018-06-04T18:14:06+00:00","dateModified":"2018-06-04T18:36:07+00:00","mainEntityOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/06\/Asamblea_AMPA_junio_2018_9.jpg","keywords":["Asambleas"],"articleSection":["AMPA","Colegio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/","name":"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso - Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","isPartOf":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/#primaryimage"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/#primaryimage"},"thumbnailUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/06\/Asamblea_AMPA_junio_2018_9.jpg","datePublished":"2018-06-04T18:14:06+00:00","dateModified":"2018-06-04T18:36:07+00:00","breadcrumb":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/#primaryimage","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/06\/Asamblea_AMPA_junio_2018_9.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/06\/Asamblea_AMPA_junio_2018_9.jpg","width":925,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/malaga.salesianos.edu\/colegio\/blog\/asamblea-general-ordinaria-de-los-socios-del-ampa-y-convivencia-fin-de-curso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/malaga.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Asamblea General Ordinaria de los socios del AMPA y Convivencia fin de curso"}]},{"@type":"WebSite","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#website","url":"https:\/\/malaga.salesianos.edu\/colegio\/","name":"Colegio Concertado San Bartolom\u00e9 | Salesianos M\u00e1laga","description":"Centro concertado. Infantil, Primaria, ESO, Bachillerato, Formaci\u00f3n Profesional, Formaci\u00f3n Profesional B\u00e1sica (FPB) y Ciclos Formativos de Grado Medio y Superior.","publisher":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malaga.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#organization","name":"Salesianos M\u00e1laga","url":"https:\/\/malaga.salesianos.edu\/colegio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/","url":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","contentUrl":"https:\/\/malaga.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/04\/MALAGAobraVN2.jpg","width":1937,"height":1490,"caption":"Salesianos M\u00e1laga"},"image":{"@id":"https:\/\/malaga.salesianos.edu\/colegio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/11948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=11948"}],"version-history":[{"count":4,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/11948\/revisions"}],"predecessor-version":[{"id":11963,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/11948\/revisions\/11963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/11949"}],"wp:attachment":[{"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=11948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=11948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malaga.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=11948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}